{"id":3850,"date":"2020-07-17T14:29:40","date_gmt":"2020-07-17T19:29:40","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=3850"},"modified":"2020-07-17T14:29:42","modified_gmt":"2020-07-17T19:29:42","slug":"policia-de-investigacion-del-delito-aseguro-droga-en-10-cateos-simultaneos-en-queretaro-y-corregidora","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/17\/policia-de-investigacion-del-delito-aseguro-droga-en-10-cateos-simultaneos-en-queretaro-y-corregidora\/","title":{"rendered":"Polic\u00eda de Investigaci\u00f3n del Delito asegur\u00f3 droga en 10 cateos simult\u00e1neos en Quer\u00e9taro y Corregidora"},"content":{"rendered":"\n<p>En atenci\u00f3n a una denuncia ciudadana elementos de la Polic\u00eda de Investigaci\u00f3n del Delito, ubicaron 10 domicilios en los municipios de Quer\u00e9taro y Corregidora. Se detuvo a 3 en posesi\u00f3n de droga, un arma, cartucho \u00fatiles y m\u00e1s de un mill\u00f3n 400 mil pesos en efectivo; dinero posiblemente producto de la venta de narc\u00f3tico.<\/p>\n\n\n\n<p>Una vez que se obtuvieron las \u00f3rdenes de cateo, por parte de un Juez de Control, se realiz\u00f3 el despliegue policial, en conjunto con la Polic\u00eda Estatal, para intervenir los 10 domicilios, en 7 colonias.<\/p>\n\n\n\n<p>Resultado de la intervenci\u00f3n policial, se aseguraron m\u00e1s de 170 bolsas de diferentes tama\u00f1os, con sustancias similares a la metanfetamina y la coca\u00edna; de igual forma, se decomisaron 800 gramos de coca\u00edna. Adem\u00e1s, un arma de fuego y cartuchos \u00fatiles.<\/p>\n\n\n\n<p>Por la cantidad de droga asegurada, corresponde a una competencia federal, por ello, un hombre y una mujer, fueron puestos a disposici\u00f3n de la Fiscal\u00eda General de la Rep\u00fablica, Delegaci\u00f3n Quer\u00e9taro. El otro detenido, ser\u00e1 presentado ante las autoridades locales, para determinar su situaci\u00f3n jur\u00eddica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En atenci\u00f3n a una denuncia ciudadana elementos de la Polic\u00eda de Investigaci\u00f3n del Delito, ubicaron 10 domicilios en los municipios de Quer\u00e9taro y Corregidora. Se detuvo a 3 en posesi\u00f3n &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/17\/policia-de-investigacion-del-delito-aseguro-droga-en-10-cateos-simultaneos-en-queretaro-y-corregidora\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":3851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qro","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=3850"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3850\/revisions"}],"predecessor-version":[{"id":3852,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3850\/revisions\/3852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/3851"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=3850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=3850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=3850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}