{"id":3899,"date":"2020-07-19T22:41:06","date_gmt":"2020-07-20T03:41:06","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=3899"},"modified":"2020-07-19T22:41:08","modified_gmt":"2020-07-20T03:41:08","slug":"en-zonas-queretanas-de-alta-marginacion-llegan-centros-integrales-de-aprendizaje-comunitario","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/19\/en-zonas-queretanas-de-alta-marginacion-llegan-centros-integrales-de-aprendizaje-comunitario\/","title":{"rendered":"En zonas queretanas de alta marginaci\u00f3n, llegan Centros Integrales de Aprendizaje Comunitario"},"content":{"rendered":"\n<p>Comunidades de muy alta marginaci\u00f3n en Quer\u00e9taro y el Gobierno de M\u00e9xico est\u00e1n trabajando en la creaci\u00f3n de Centros Integrales de Aprendizaje Comunitario (CIACS), lo que significa dar un paso m\u00e1s ambicioso en las posibilidades que brinda el Programa \u201cLa Escuela Es Nuestra\u201d en cuanto a realizar&nbsp;trabajos de construcci\u00f3n, mantenimiento y equipamiento en favor la&nbsp;educaci\u00f3n b\u00e1sica que recibe la ni\u00f1ez mexicana.<\/p>\n\n\n\n<p>En la entidad, son alrededor de 350 escuelas las que han sido beneficiadas con al menos 150 mil pesos cada una, las cuales pertenecen tanto a la&nbsp;Unidad de Servicios para la Educaci\u00f3n B\u00e1sica en el Estado de Quer\u00e9taro (USEBEQ), como a la Comisi\u00f3n Nacional de Fomento Educativo (Conafe). Los&nbsp;recursos p\u00fablicos que se les asignan son administrados por padres de familia y maestros a trav\u00e9s de los&nbsp;Comit\u00e9s Escolares de Administraci\u00f3n Participativa.<\/p>\n\n\n\n<p>El Delegado Estatal de Programas para el Desarrollo, Dr. Gilberto Herrera Ruiz, detall\u00f3 que en este momento se est\u00e1n creando 10 CIACS en Quer\u00e9taro, con la voluntad de diversas comunidades beneficiadas con el programa LEEN que han determinado unir esfuerzos, as\u00ed como el financiamiento que recib\u00eda cada escuela con el prop\u00f3sito de generar un proyecto educativo m\u00e1s ambicioso.<\/p>\n\n\n\n<p>\u201cLos CIACS ser\u00e1n planteles donde se concentrar\u00e1n dos o m\u00e1s escuelas de nivel b\u00e1sico de diferentes localidades. Es decir, si en una comunidad hab\u00eda primaria, en otra un k\u00ednder y en otra secundaria, \u00e9stas se est\u00e1n juntando en puntos intermedios para crear la sede del CIAC y ah\u00ed tener varios niveles escolares, con otros servicios como un comedor, biblioteca y espacios deportivos\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Estos Centros Integrales se est\u00e1n desarrollando en los municipios de Pinal de Amoles, Jalpan, Tolim\u00e1n, Quer\u00e9taro, Landa de Matamoros, Pe\u00f1amiller y San Joaqu\u00edn, con la participaci\u00f3n de m\u00e1s de 20 comunidades.<\/p>\n\n\n\n<p>\u201cCada escuela LEEN recibe al menos 150 mil pesos, dependiendo el n\u00famero de alumnos. Al decidir unirse para integrar un CIAC, el gobierno federal incrementa esa inversi\u00f3n para que cada escuela aporte 500 mil pesos y se tenga un monto mayor que permita echar andar el proyecto bajo los mismos t\u00e9rminos de que sean las comunidades las que hagan los trabajos de construcci\u00f3n y administren el dinero p\u00fablico que se les da para ese fin\u201d, indic\u00f3 el Dr. Herrera Ruiz.<\/p>\n\n\n\n<p>Al respecto el se\u00f1or Arnulfo Linares, padre de familia y maestro de los trabajos de alba\u00f1iler\u00eda en la obra del CIAC en Pe\u00f1amiller, consider\u00f3 que este proyecto representa una gran oportunidad para que las ni\u00f1as y ni\u00f1os encuentren una mayor motivaci\u00f3n, y para que las comunidades se fortalezcan en confianza y en el compromiso de trabajar por objetivos comunes; ahora est\u00e1n reunidos en torno a la educaci\u00f3n, pero igualmente espera que puedan hacerlo en temas de caminos y salud.<\/p>\n\n\n\n<p>\u201cMe siento contento, a gusto en esta obra para darle motivaci\u00f3n a los ni\u00f1os. Llevamos ahorita siete semanas, con toda la gente, ech\u00e1ndole ganas, de principio \u00e9ramos seis alba\u00f1iles, ahorita somos ocho, todos somos de las comunidades de por aqu\u00ed. Y f\u00edjese que como comunidad hemos platicado eso de que seamos nosotros los que estemos construyendo y estamos muy conformes porque as\u00ed nosotros, con el dinero que llega directo, avanzamos m\u00e1s los trabajos y hacemos rendir el dinero\u201d, asegur\u00f3.<\/p>\n\n\n\n<p>El Dr. Herrera Ruiz -titular de la Delegaci\u00f3n Quer\u00e9taro de la Secretar\u00eda de Bienestar- enfatiz\u00f3 que, aunado a los servicios educativos de los CIACS, se tiene el objetivo de que en esos espacios se detonen otros procesos comunitarios que permitan el empoderamiento de las localidades, para hacer frente a otras necesidades y problem\u00e1ticas, as\u00ed como para echar andar proyectos productivos, de mejora a la infraestructura de caminos y buscar condiciones de vida m\u00e1s favorables.<\/p>\n\n\n\n<p>La creaci\u00f3n de estos CIACS, as\u00ed como los trabajos de las escuelas del programa LEEN, est\u00e1n siendo acompa\u00f1ados por estudiantes, egresados y profesores de la Facultad de Ingenier\u00eda de la Universidad Aut\u00f3noma de Quer\u00e9taro y por parte del Gobierno de M\u00e9xico se tiene apertura total para sumar esfuerzos con otras instituciones que igualmente deseen aportar para mejorar la educaci\u00f3n p\u00fablica en M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunidades de muy alta marginaci\u00f3n en Quer\u00e9taro y el Gobierno de M\u00e9xico est\u00e1n trabajando en la creaci\u00f3n de Centros Integrales de Aprendizaje Comunitario (CIACS), lo que significa dar un paso &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/19\/en-zonas-queretanas-de-alta-marginacion-llegan-centros-integrales-de-aprendizaje-comunitario\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":3900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qro","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=3899"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3899\/revisions"}],"predecessor-version":[{"id":3901,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3899\/revisions\/3901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/3900"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=3899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=3899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=3899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}