{"id":3989,"date":"2020-07-21T14:28:49","date_gmt":"2020-07-21T19:28:49","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=3989"},"modified":"2020-07-21T14:28:51","modified_gmt":"2020-07-21T19:28:51","slug":"durante-la-pandemia-aumentan-homicidios-en-mexico","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/21\/durante-la-pandemia-aumentan-homicidios-en-mexico\/","title":{"rendered":"Durante la pandemia, aumentan homicidios en M\u00e9xico"},"content":{"rendered":"\n<p><strong>El n\u00famero de homicidios en M\u00e9xico ha aumentado durante la pandemia de coronavirus<\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>A estas cifras se les puede icnluir un repunte de 9,2% en los asesinatos de mujeres, de acuerdo con cifras del gobierno publicadas el lunes.<\/p>\n\n\n\n<p>Los datos de la primera mitad de 2020 muestran que los homicidios subieron 1,9%, a 17.982, respecto a los 17.653 registrados en el mismo periodo del a\u00f1o pasado.<\/p>\n\n\n\n<p>Los activistas tem\u00edan desde hace tiempo que el confinamiento de familias debido al virus generar\u00eda un aumento en los asesinatos de mujeres, y de hecho as\u00ed ocurri\u00f3, de 448 en el primer semestre de 2019 a 489 en el mismo periodo de este a\u00f1o.<\/p>\n\n\n\n<p>Alejandro Hope, analista de seguridad de M\u00e9xico, escribi\u00f3 en una columna publicada el lunes que los c\u00e1rteles han hecho demostraciones de poder similares o m\u00e1s grandes en el pasado, y que el c\u00e1rtel de Jalisco probablemente evitar\u00eda un enfrentamiento directo con el Ej\u00e9rcito. Pero se\u00f1al\u00f3 que se requieren m\u00e1s patrullajes rurales para que el gobierno establezca el control.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cNo se debe minimizar la importancia de los videos, pero tampoco son un hecho sin precedentes\u201d, escribi\u00f3 Hope. \u201cSin embargo, el hecho de que estas cosas se repitan una y otra vez son una muestra de la debilidad estructural del estado mexicano. Eso es lo que deber\u00edamos estar discutiendo\u201d.<\/p><\/blockquote>\n\n\n\n<p>La Secretar\u00eda de Seguridad P\u00fablica hizo notar en su informe que la tasa de incremento de los homicidios ha disminuido un poco. Pero es probable que el persistente nivel elevado en los asesinatos atraiga a\u00fan m\u00e1s atenci\u00f3n sobre la pol\u00edtica del presidente Andr\u00e9s Manuel L\u00f3pez Obrador de evitar una confrontaci\u00f3n directa con los c\u00e1rteles. El mandatario prefiere atender los problemas sociales como la pobreza y el desempleo que, dice, contribuyen al crimen organizado.<\/p>\n\n\n\n<p>Pero L\u00f3pez Obrador les ha asignado a las fuerzas de seguridad federales \u2014al Ej\u00e9rcito, la Marina Armada y la reci\u00e9n creada Guardia Nacional\u2014 tantos deberes aparte de hacer respetar la ley que parecer\u00edan estar cortos de personal para abordar el problema de los choques entre los c\u00e1rteles de la droga.<\/p>\n\n\n\n<p>Los efectos del confinamiento sobre la delincuencia fueron variados y en algunos casos no est\u00e1n claros. Las autoridades reportaron un aumento de 12,1% en los casos de tr\u00e1fico de drogas a nivel de calle durante el primer semestre del a\u00f1o, pero se desconoce si eso se debi\u00f3 a que hubo menor tr\u00e1nsito de gente debido al coronavirus, lo que pudo haberle facilitado a la polic\u00eda la detecci\u00f3n de las ventas de droga.<\/p>\n\n\n\n<p>La pandemia s\u00ed parece haber generado un fuerte descenso en algunos tipos de delitos. Debido a que mucho menos personas est\u00e1n transport\u00e1ndose en autobuses, los asaltos a pasajeros del transporte p\u00fablico bajaron 45,1% durante los primeros seis meses del a\u00f1o, y los secuestros disminuyeron 37,3% respecto al mismo periodo de 2019. Otros tipos de robos tambi\u00e9n descendieron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El n\u00famero de homicidios en M\u00e9xico ha aumentado durante la pandemia de coronavirus Redacci\u00f3n A estas cifras se les puede icnluir un repunte de 9,2% en los asesinatos de mujeres, &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/21\/durante-la-pandemia-aumentan-homicidios-en-mexico\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":3991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nal","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=3989"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3989\/revisions"}],"predecessor-version":[{"id":3992,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/3989\/revisions\/3992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/3991"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=3989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=3989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=3989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}