{"id":4013,"date":"2020-07-21T16:14:24","date_gmt":"2020-07-21T21:14:24","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4013"},"modified":"2020-07-21T16:14:25","modified_gmt":"2020-07-21T21:14:25","slug":"la-delincuencia-organizada-en-ensenorea-con-amlo","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/21\/la-delincuencia-organizada-en-ensenorea-con-amlo\/","title":{"rendered":"La delincuencia organizada en ense\u00f1orea con AMLO"},"content":{"rendered":"\n<p>TRAS LA VERDAD por H\u00e9ctor Parra Rodr\u00edguez. @HectorParraRgz<\/p>\n\n\n\n<p>El Presidente de la Rep\u00fablica Andr\u00e9s Manuel L\u00f3pez, mantiene ocupadas a las fuerzas armadas en actividades de alba\u00f1iler\u00eda, construyendo un aeropuerto; desde la semana pasada tambi\u00e9n atienden aduanas y contin\u00faan en la b\u00fasqueda de predios para la construcci\u00f3n de las oficinas de los Banquitos del Bienestar, entre otras actividades; a la fuerza de la Guardia Nacional, la ocupa para cuidar las fronteras, cumpliendo el acuerdo con Donald Trump. Miles de elementos de las fuerzas de seguridad p\u00fablica ocupados en actividades que no son de su competencia. De ah\u00ed que las fuerzas de combate del Estado que debieran perseguir a la delincuencia organizada, hayan sido diezmadas voluntariamente por orden presidencial, mientras aquellos crecen y act\u00faan son control.<\/p>\n\n\n\n<p>Entre tanto, el Presidente distrae a los mexicanos por medio de sus conferencias medi\u00e1ticas, con el asunto de Emilio Lozoya y sube de importancia un video que navega en redes sociales \u2013los medios de comunicaci\u00f3n tradicionales hicieron eco de la informaci\u00f3n-, en el que un grupo delincuencial hace gala de su fuerza destructiva y de combate, mostrando un grupo de \u201c\u00e9lite\u201d, \u201carmados hasta los dientes\u201d con equipo de ataque pesado, tambi\u00e9n camuflageados. Ellos s\u00ed utilizan su fuerza, a diferencia de lo ordenando por el Presidente. Armamento en manos de la delincuencia que no tiene ninguna autoridad estatal, mucho menos municipal; apenas el personal del Ej\u00e9rcito Mexicano tiene ese potencial, pero le est\u00e1 prohibido utilizarlo en contra del \u201cpueblo\u201d.<\/p>\n\n\n\n<p>Para colmo, en una de sus conferencias el Presidente confronta \u2013se entretiene- con lo dicho por un periodista en relaci\u00f3n al tema de la fuerza mostrada por la delincuencia organizada. Apenas hace un par de semanas, otro delincuente \u2013\u201cEl Marro\u201d- acapar\u00f3 la atenci\u00f3n medi\u00e1tica debido a la detenci\u00f3n de sus familiares, amenazando a las autoridades por ese hecho; familiares que de inmediato salieron del reclusorio por \u201cerrores de procedimiento\u201d. Total, la \u201cbatalla\u201d en contra de la delincuencia, por parte del gobierno federal, se da en las conferencias y redes sociales, no en los hechos; mientras los delincuentes dan la batalla con actos delincuenciales, llevan a la realidad los actos violentos \u00bfY la sociedad? A merced de los grupos de la delincuencia organizada, competencia de la autoridad federal y Fiscal\u00eda General, que no logran controlar. Ante la ineptitud e inactividad del gobierno, los criminales se atreven a lanzar amenazas en contra de altos funcionarios \u00bfC\u00f3mo pueden confiar los gobernadores del ofrecimiento de apoyo de L\u00f3pez Obrador? Este prometi\u00f3 apoyarlos en contra de la delincuencia organizada \u00bfC\u00f3mo? Los hechos lo desmienten. M\u00e1s parecen aliados del gobierno federal, que enemigos p\u00fablicos a combatir<\/p>\n\n\n\n<p>El Presidente refuerza su falso discurso sobre Lozoya. Mencion\u00f3 que aquel ya declar\u00f3 ante la Fiscal\u00eda General de la Rep\u00fablica, cuando esta \u2013Gertz Manero- debi\u00f3 ponerlo de inmediato a disposici\u00f3n del juez que lo reclama; solo ante esa autoridad puede declarar para que sea legalmente v\u00e1lida su confesi\u00f3n. A L\u00f3pez lo que le importa son los nombres de aquellos que pueden estar relacionados con los delitos que le imputan al detenido, le representa un \u201cbot\u00edn pol\u00edtico\u201d. Lo que no pondera o nada le importa al Presidente, que los actos realizados fuera del \u00e1mbito de la competencia judicial, est\u00e1n afectados de plena nulidad, carecen de todo valor jur\u00eddico en el proceso. Lozoya fue detenido por orden de un juez, luego debieron ponerlo a disposici\u00f3n de este. No se trat\u00f3 de detenci\u00f3n in fraganti en la comisi\u00f3n del hecho delictivo, para que primero declarase ante el Ministerio P\u00fablico y despu\u00e9s lo ponga a disposici\u00f3n de la autoridad judicial \u00a1No fue as\u00ed! Los t\u00e9rminos legales siguen corriendo y el detenido sigue en el hospital \u00bfCu\u00e1l es entonces la pretensi\u00f3n de L\u00f3pez? \u00bfQu\u00e9 instrucciones sigue Gertz Manero? \u00bfSimplemente distraer y ensuciar el proceso penal para despu\u00e9s liberar al inculpado por violaciones al debido proceso? Todo un espect\u00e1culo medi\u00e1tico.<\/p>\n\n\n\n<p>Por estas y muchas m\u00e1s razones la delincuencia se \u201cense\u00f1orea\u201d mostrando \u201cel m\u00fasculo de fuerza letal\u201d. Muestran su ej\u00e9rcito paralelo, al que el Presidente le resta importancia, prefiere \u201ccombatir\u201d medi\u00e1ticamente a sus oponentes pol\u00edticos y \u201catacar\u201d a medios de comunicaci\u00f3n por la informaci\u00f3n que difunden; hace caso omiso a los delincuentes, ni los ve ni los oye. Un gobierno que prueba reiteradamente su ineptitud con descaro, lo presume el titular del Poder Ejecutivo, que no se intimida ante sus enemigos pol\u00edticos, a estos no los tolera. Mientras a la delincuencia la deja actuar libremente, prefiere evadir responsabilidad y temas delicados que afectan a millones de mexicanos. No olvidemos que en 18 meses del gobierno de Andr\u00e9s Manuel, van m\u00e1s de 50 mil homicidios dolosos.<\/p>\n\n\n\n<p>Para colmo. Cuando llega Emilio Lozoya a M\u00e9xico, el Fiscal Alejandro Gertz Manero, se burla del Presidente. Le hace creer que fue recluido en un Centro de Reinserci\u00f3n Social, por eso torpemente lo declaro y confirm\u00f3 su Secretario de Seguridad P\u00fablica. En plena conferencia period\u00edstica quedaron en total rid\u00edculo. Lozoya no fue recluido en ning\u00fan Centro, lo llevaron a un hospital de lujo para ser atendido de su salud. En la conferencia, con titubeos tuvieron que recular despu\u00e9s del gazapo informativo. As\u00ed de desinformado el Presidente que a diario presume reunirse con su gabinete de seguridad para atender asuntos de la materia. Al momento, Emilio Lozoya Austin, sigue \u201crecluido\u201d en el hospital de lujo. L\u00f3pez afirm\u00f3 esta ma\u00f1ana que ya declar\u00f3 ante el Fiscal y dio nombres de involucrados. Insisto \u00bfQui\u00e9n inform\u00f3 al Presidente lo que ha dicho Emilio? No es lo mismo que declarar ante la autoridad competente \u00bfY el Juez de la causa? Definitivamente el procedimiento penal lo est\u00e1n violentando, ensuciando en beneficio del detenido \u00bfPerverso o ignorante el Presidente? Razones suficientes tiene la delincuencia organizada para ense\u00f1orearse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRAS LA VERDAD por H\u00e9ctor Parra Rodr\u00edguez. @HectorParraRgz El Presidente de la Rep\u00fablica Andr\u00e9s Manuel L\u00f3pez, mantiene ocupadas a las fuerzas armadas en actividades de alba\u00f1iler\u00eda, construyendo un aeropuerto; desde &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/21\/la-delincuencia-organizada-en-ensenorea-con-amlo\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-4013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4013"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4013\/revisions"}],"predecessor-version":[{"id":4015,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4013\/revisions\/4015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4014"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}