{"id":4057,"date":"2020-07-22T10:42:05","date_gmt":"2020-07-22T15:42:05","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4057"},"modified":"2020-07-22T10:42:07","modified_gmt":"2020-07-22T15:42:07","slug":"mexico-rebasa-los-40-mil-muertos-por-covid-19","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/22\/mexico-rebasa-los-40-mil-muertos-por-covid-19\/","title":{"rendered":"M\u00e9xico rebasa los 40 mil muertos por COVID-19"},"content":{"rendered":"\n<p><strong>M\u00e9xico rebas\u00f3 los 40.000 muertos por COVID-19 e inform\u00f3 que la cifra de nuevos casos diarios se aproxim\u00f3 a sus m\u00e1ximos hist\u00f3ricos<\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>La Secretar\u00eda de Salud dijo que se registraron 915 decesos adicionales, para elevar el total a 40.400, el cuarto m\u00e1s alto despu\u00e9s de los 45.507 de Gran Breta\u00f1a.<\/p>\n\n\n\n<p>Las infecciones confirmadas aumentaron en 6.859 a 356.386 en M\u00e9xico, para alcanzar cifras similares a las de Per\u00fa con la sexta mayor cantidad de infecciones. Sin embargo, se considera que el n\u00famero de contagios es mucho mayor a las cifras oficiales debido a la poca cantidad de pruebas de diagn\u00f3stico que se realizan en el pa\u00eds.<\/p>\n\n\n\n<p>Para el martes, M\u00e9xico hab\u00eda realizado poco m\u00e1s de 820.000 pruebas de diagn\u00f3stico, es decir una por cada 160 habitantes. En las \u00faltimas semanas, 47% de todas las pruebas han dado positivo, lo que deja entrever que en M\u00e9xico solo se realizan an\u00e1lisis a aquellas personas con s\u00edntomas graves.<\/p>\n\n\n\n<p>Las autoridades de salud han indicado que al pa\u00eds solo tiene alrededor de 170.000 pruebas de diagn\u00f3stico disponibles, pero dejaron abierta la posibilidad de adquirir m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico rebas\u00f3 los 40.000 muertos por COVID-19 e inform\u00f3 que la cifra de nuevos casos diarios se aproxim\u00f3 a sus m\u00e1ximos hist\u00f3ricos Redacci\u00f3n La Secretar\u00eda de Salud dijo que se &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/22\/mexico-rebasa-los-40-mil-muertos-por-covid-19\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nal","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4057"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4057\/revisions"}],"predecessor-version":[{"id":4059,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4057\/revisions\/4059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4058"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}