{"id":4070,"date":"2020-07-22T10:59:28","date_gmt":"2020-07-22T15:59:28","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4070"},"modified":"2020-07-22T10:59:29","modified_gmt":"2020-07-22T15:59:29","slug":"embajada-de-china-en-whashington-recibe-amenazas-de-bomba","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/22\/embajada-de-china-en-whashington-recibe-amenazas-de-bomba\/","title":{"rendered":"Embajada de China en Whashington recibe amenazas de bomba"},"content":{"rendered":"\n<p><strong><em>Estados Unidos orden\u00f3 a China cerrar su consulado en Houston para proteger la propiedad intelectual y la informaci\u00f3n privada de los estadounidenses<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEstados Unidos no tolerar\u00e1 m\u00e1s violaciones (de China) de nuestra soberan\u00eda e intimidaci\u00f3n de nuestro pueblo, as\u00ed como tampoco hemos tolerado (sus) pr\u00e1cticas comerciales injustas, el robo de empleos estadounidenses y otros comportamientos atroces\u201d, apunt\u00f3 el comunicado, que fue atribuido al vocero del Departamento de Estado, Morgan Ortagus.<\/p><\/blockquote>\n\n\n\n<p>China conden\u00f3 la decisi\u00f3n, que se produce en un momento de crecientes tensiones entre las dos mayores econom\u00edas del mundo en temas como econom\u00eda, comercio, tecnolog\u00eda, derechos humanos y seguridad.<\/p>\n\n\n\n<p>En Houston, bomberos respondieron a una denuncia de que hab\u00eda papeles quem\u00e1ndose en los terrenos del consulado el martes en la noche, pero no se les permiti\u00f3 el acceso, report\u00f3 la prensa local.<\/p>\n\n\n\n<p>Estados Unidos no proporcion\u00f3 m\u00e1s detalles sobre sus acusaciones en su breve comunicado.<\/p>\n\n\n\n<p>El secretario de Estado Mike Pompeo dijo que la administraci\u00f3n de presidente Donald Trump est\u00e1 tomando medidas para detener el robo de propiedad intelectual de larga data, y mencion\u00f3 las acusaciones anunciadas el martes contra dos presuntos hackers chinos.<\/p>\n\n\n\n<p>Estados Unidos tambi\u00e9n decidi\u00f3 no reabrir su consulado en la ciudad de Wuhan, que se cerr\u00f3 a fines de enero en lo \u00e1lgido del brote de coronavirus en China, dijo un funcionario de la administraci\u00f3n Trump.<\/p>\n\n\n\n<p>Beijing fue informado de la decisi\u00f3n el martes, dijo el portavoz del Ministerio de Relaciones Exteriores de China, Wang Wenbin, quien calific\u00f3 lo ocurrido como una \u201cacci\u00f3n escandalosa e injustificada que sabotear\u00e1 las relaciones entre los dos pa\u00edses\u201d.<\/p>\n\n\n\n<p><strong>Adem\u00e1s de su embajada en Beijing, Estados Unidos tiene cinco consulados en China: Shangh\u00e1i, Guangzhou, Chengdu, Wuhan y Shenyang.<\/strong><\/p>\n\n\n\n<p>La prensa en Houston inform\u00f3 que las autoridades respondieron a reportes sobre un incendio en el consulado. Seg\u00fan testigos, hab\u00eda gente quemando papeles en lo que parec\u00edan ser botes de basura, report\u00f3 el Houston Chronicle citando a la polic\u00eda.<\/p>\n\n\n\n<p><strong>La embajada china en Washington ha recibido amenazas de bomba y de muerte, a\u00f1adi\u00f3, culpando a Estados Unidos de avivar el odio contra China.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos orden\u00f3 a China cerrar su consulado en Houston para proteger la propiedad intelectual y la informaci\u00f3n privada de los estadounidenses Redacci\u00f3n \u201cEstados Unidos no tolerar\u00e1 m\u00e1s violaciones (de &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/22\/embajada-de-china-en-whashington-recibe-amenazas-de-bomba\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inter","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4070"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4070\/revisions"}],"predecessor-version":[{"id":4072,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4070\/revisions\/4072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4071"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}