{"id":4078,"date":"2020-07-22T11:13:47","date_gmt":"2020-07-22T16:13:47","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4078"},"modified":"2020-07-22T11:13:49","modified_gmt":"2020-07-22T16:13:49","slug":"comienzan-a-definirse-los-octavos-de-final-de-la-mls","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/22\/comienzan-a-definirse-los-octavos-de-final-de-la-mls\/","title":{"rendered":"Comienzan a definirse los octavos de final de la MLS"},"content":{"rendered":"\n<p><strong>El Crew de Columbus, el Revolution de Nueva Inglaterra y el Toronto FC sellaron el martes sus pasajes respectivos para los octavos de la MLS<\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Columbus super\u00f3 1-0 al Atlanta United, merced a un tanto de Younees Mokhtar a los 18 minutos, para clasificarse desde el Grupo E, con tres victorias en el mismo n\u00famero de partidos, en los que no recibi\u00f3 un solo gol.<\/p>\n\n\n\n<p>M\u00e1s temprano, Nueva Inglaterra y Toronto no pasaron del empate sin goles, resultado que bast\u00f3 para que ambos equipos avanzaran.<\/p>\n\n\n\n<p>A diferencia del Crew, Atlanta, que se coron\u00f3 en la MLS hace dos a\u00f1os y avanz\u00f3 a la final de la Conferencia del Este la campa\u00f1a anterior, perdi\u00f3 sus tres partidos de la fase de grupos en este torneo. Es el \u00fanico de los 24 participantes que no consigui\u00f3 un solo gol.<\/p>\n\n\n\n<p>El argentino Milton Valenzuela prodig\u00f3 la asistencia para el tanto de Mokhtar. Le envi\u00f3 un servicio desde la parte izquierda del \u00e1rea.<\/p>\n\n\n\n<p>Pese a estar rodeado por tres defensas de Atlanta, el marroqu\u00ed alcanz\u00f3 a realizar el disparo. El bal\u00f3n pareci\u00f3 desviarse en un pie de Miles Robinson, lo que habr\u00eda confundido al arquero Brad Guzan.<\/p>\n\n\n\n<p>El Crew tiene asegurado tambi\u00e9n el primer puesto del grupo. Los Red Bulls de Nueva York y el Cincinnati FC tienen tres puntos cada uno y se enfrentar\u00e1n este mi\u00e9rcoles en pos del otro pasaje.<\/p>\n\n\n\n<p>En el empate entre Nueva Inglaterra y Toronto, la figura fue Matt Turner, el arquero del Revolution. Ataj\u00f3 una media docena de remates a gol, destac\u00e1ndose una intervenci\u00f3n para repeler el disparo de Ayo Akinola cerca del final.<\/p>\n\n\n\n<p>El delantero Jozy Altidore debut\u00f3 con Toronto en el torneo \u201cMLS is Back\u201d, ingresando como suplente a los 86 minutos.<\/p>\n\n\n\n<p>Tanto Nueva Inglaterra como Toronto terminaron con cinco puntos en el Grupo C, pero el equipo canadiense tiene mejor diferencia de goles.<\/p>\n\n\n\n<p>En el \u00faltimo partido de la jornada, cuyo \u00fanico inter\u00e9s estaba en definir al tercero y cuarto lugar del Grupo C, el Impact de Montreal se impuso 1-0 al D.C. United.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Crew de Columbus, el Revolution de Nueva Inglaterra y el Toronto FC sellaron el martes sus pasajes respectivos para los octavos de la MLS Redacci\u00f3n Columbus super\u00f3 1-0 al &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/22\/comienzan-a-definirse-los-octavos-de-final-de-la-mls\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4078"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4078\/revisions"}],"predecessor-version":[{"id":4080,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4078\/revisions\/4080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4079"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}