{"id":4218,"date":"2020-07-24T15:46:00","date_gmt":"2020-07-24T20:46:00","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4218"},"modified":"2020-07-24T15:46:01","modified_gmt":"2020-07-24T20:46:01","slug":"la-tormenta-tropical-hanna-se-acerca-a-las-costas-de-texas","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/24\/la-tormenta-tropical-hanna-se-acerca-a-las-costas-de-texas\/","title":{"rendered":"La tormenta tropical Hanna se acerca a las costas de Texas"},"content":{"rendered":"\n<p><strong>La tormenta tropical Hanna adquiri\u00f3 un poco de fuerza el viernes en su avance hacia la costa de Texas, amenazando con intensas lluvias, marejadas y fuertes vientos<\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Hanna estaba a unos 375 kil\u00f3metros (230 millas) al este de Corpus Christi, Texas, dijo el Centro Nacional de Huracanes de Estados Unidos (NHC, por sus siglas en ingl\u00e9s) en su aviso de la 1 de la tarde. El meteoro ten\u00eda vientos m\u00e1ximos sostenidos de 85 km\/h (50 mph) y se desplazaba en direcci\u00f3n oeste-noroeste a 15 km\/h (9 mph).<\/p>\n\n\n\n<p>Los expertos prev\u00e9n que la tormenta toque tierra el s\u00e1bado. Est\u00e1 vigente un aviso preventivo para la regi\u00f3n comprendida entre la desembocadura del R\u00edo Bravo y San Luis Pass, Texas.<\/p>\n\n\n\n<p>Los meteor\u00f3logos se\u00f1alaron que Hanna podr\u00eda dejar precipitaciones de entre 10 y 20 cent\u00edmetros (entre 4 y 8 pulgadas) de lluvia y causar oleaje peligroso y corrientes de resaca.<\/p>\n\n\n\n<p>Se prev\u00e9 que Hanna arroje entre 10 y 20 cent\u00edmetros (de 4 a 8 pulgadas) de lluvia y provoque marejadas acompa\u00f1adas de peligrosas olas altas y corrientes de resaca.<\/p>\n\n\n\n<p>En tanto, Gonzalo avanzaba a 30 km\/h (18 mph) con vientos m\u00e1ximos sostenidos de 75 km\/h (45 mph), dijo el Centro Nacional de Huracanes en su actualizaci\u00f3n vespertina del viernes. Se ubicaba a 715 kil\u00f3metros (445 millas) al este de las Islas de Barlovento.<\/p>\n\n\n\n<p>El NHC se\u00f1al\u00f3 que los habitantes de las Islas de Barlovento deben estar pendientes de la tormenta porque est\u00e1 previsto que se acerque a la zona el viernes por la noche y el s\u00e1bado. Es posible que adquiera un poco de fuerza aunque se prev\u00e9 que se debilite durante su avance hacia el mar caribe.<\/p>\n\n\n\n<p>Se emiti\u00f3 un aviso de hurac\u00e1n para Barbados y San Vicente y las Granadinas. Un aviso de tormenta tropical est\u00e1 en vigor para Santa Luc\u00eda, Tobago, Granada y otras islas. Seg\u00fan las previsiones, Gonzalo podr\u00eda arrojar entre 5 y 13 cent\u00edmetros (de 2 a 5 pulgadas) de lluvia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tormenta tropical Hanna adquiri\u00f3 un poco de fuerza el viernes en su avance hacia la costa de Texas, amenazando con intensas lluvias, marejadas y fuertes vientos Redacci\u00f3n Hanna estaba &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/24\/la-tormenta-tropical-hanna-se-acerca-a-las-costas-de-texas\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inter","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4218"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4218\/revisions"}],"predecessor-version":[{"id":4223,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4218\/revisions\/4223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4221"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}