{"id":4242,"date":"2020-07-24T16:01:24","date_gmt":"2020-07-24T21:01:24","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4242"},"modified":"2020-07-24T16:01:25","modified_gmt":"2020-07-24T21:01:25","slug":"la-oms-asegura-que-aun-no-existe-inmunidad-de-grupo","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/24\/la-oms-asegura-que-aun-no-existe-inmunidad-de-grupo\/","title":{"rendered":"La OMS asegura que aun no existe inmunidad de grupo"},"content":{"rendered":"\n<p><strong>Entre el 50 y el 60% de la poblaci\u00f3n mundial tendr\u00eda que ser inmune al coronavirus para que exista lo que se conoce como \u201cinmunidad de grupo\u201d y aun no se consigue<\/strong><\/p>\n\n\n\n<p><em><strong>Redacci\u00f3n<\/strong><\/em><\/p>\n\n\n\n<p>La inmunidad de grupo suele lograrse a trav\u00e9s de las vacunas y se da cuando la mayor\u00eda de la poblaci\u00f3n es inmune a una enfermedad, bloqueando su propagaci\u00f3n.<\/p>\n\n\n\n<p>Durante un acto en redes sociales, la doctora Soumya Swaminathan explic\u00f3 que los estudios realizados en los pa\u00edses m\u00e1s afectados por la pandemia mostraban que solo entre el 5 y el 10% de la poblaci\u00f3n tiene anticuerpos, aunque en algunos se alcanz\u00f3 hasta el 20%.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cA medida que haya oleadas de esta infecci\u00f3n en los pa\u00edses, la gente va a desarrollar anticuerpos y es de esperar que sean inmunes durante alg\u00fan tiempo, as\u00ed que tambi\u00e9n actuar\u00e1n como barreras y frenos a la propagaci\u00f3n\u00bb, se\u00f1al\u00f3.<\/p><\/blockquote>\n\n\n\n<p>Otros expertos han estimado que se necesita que hasta el 70 o el 80% de la poblaci\u00f3n tenga anticuerpos para lograr ese efecto protector.<\/p>\n\n\n\n<p>En las primeras etapas de la pandemia, pa\u00edses como Gran Breta\u00f1a propusieron lograr la inmunidad de grupo como estrategia de respuesta al COVID-19. Pero Swaminathan destac\u00f3 que lograr este efecto con una vacunas es mucho m\u00e1s seguro que dejar que el virus se extienda entre la poblaci\u00f3n.<\/p>\n\n\n\n<p>Para obtener la inmunidad de grupo a trav\u00e9s de una infecci\u00f3n natural se necesitan varias oledas de contagios con una morbilidad y mortalidad como las actuales, agreg\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 50 y el 60% de la poblaci\u00f3n mundial tendr\u00eda que ser inmune al coronavirus para que exista lo que se conoce como \u201cinmunidad de grupo\u201d y aun no &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/24\/la-oms-asegura-que-aun-no-existe-inmunidad-de-grupo\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inter","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4242"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4242\/revisions"}],"predecessor-version":[{"id":4245,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4242\/revisions\/4245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4243"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}