{"id":4272,"date":"2020-07-25T01:44:10","date_gmt":"2020-07-25T06:44:10","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4272"},"modified":"2020-07-25T01:44:12","modified_gmt":"2020-07-25T06:44:12","slug":"confirman-dos-casos-positivos-con-covid19-en-centro-penitenciario-varonil","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/25\/confirman-dos-casos-positivos-con-covid19-en-centro-penitenciario-varonil\/","title":{"rendered":"Confirman dos casos positivos con COVID19 en Centro Penitenciario Varonil"},"content":{"rendered":"\n<p>Se detectaron dos casos positivos de COVID-19 en personas privadas de la libertad en el Centro Penitenciario Varonil CP1 de San Jos\u00e9 el Alto, Quer\u00e9taro.<\/p>\n\n\n\n<p>A partir de las acciones de prevenci\u00f3n que implement\u00f3 el Sistema Penitenciario del Estado, establecidas en el acuerdo de salubridad dictado en marzo por la Secretar\u00eda de Salud estatal, en correspondencia con los acuerdos de la autoridad sanitaria federal, se monitorea permanentemente a la poblaci\u00f3n penitenciaria, al personal administrativo y t\u00e9cnico, as\u00ed como a custodios y polic\u00edas procesales.<\/p>\n\n\n\n<p>Estas medidas fueron revisadas por la Comisi\u00f3n Nacional de Derechos Humanos (CNDH) y se determin\u00f3 que eran adecuadas ante la contingencia sanitaria, para detectar eventuales brotes por la pandemia, a fin de aislar los casos positivos y proteger al resto de la poblaci\u00f3n penitenciaria.<\/p>\n\n\n\n<p>En seguimiento a esta serie de protocolos y medidas, fueron detectadas dos personas con algunos de los s\u00edntomas asociados a la enfermedad y de inmediato fueron canalizadas para brindarles atenci\u00f3n m\u00e9dica, tomar sus muestras y aplicar la prueba de confirmaci\u00f3n de COVID-19. El jueves 23 de julio la Secretar\u00eda de Salud entreg\u00f3 el resultado positivo en ambos casos.<\/p>\n\n\n\n<p>Cuando se obtuvo la confirmaci\u00f3n, las personas ya estaban aisladas de cualquier contacto f\u00edsico con el resto de las personas privadas de la libertad.<\/p>\n\n\n\n<p>El personal m\u00e9dico realiz\u00f3 la cadena de seguimiento con las personas que tuvieron contacto en d\u00edas anteriores, a quienes tambi\u00e9n se les aplicaron los tratamientos de salubridad respectivos.<\/p>\n\n\n\n<p>Al momento no existe ning\u00fan otro caso detectado, las personas ubicadas en la posible cadena de contagio se encuentran en vigilancia y sin s\u00edntoma alguno, en tanto que las personas contagiadas se encuentran en buen estado de salud y bajo estricta supervisi\u00f3n.<\/p>\n\n\n\n<p>De igual modo, se han reforzado las medidas de salubridad, con el objetivo de verificar a la poblaci\u00f3n penitenciaria e identificar oportunamente si hubiera un nuevo contagio.<\/p>\n\n\n\n<p>Dichas acciones se llevan a cabo por el personal de salud del Sistema Penitenciario en coordinaci\u00f3n con Servicios de Salud del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se detectaron dos casos positivos de COVID-19 en personas privadas de la libertad en el Centro Penitenciario Varonil CP1 de San Jos\u00e9 el Alto, Quer\u00e9taro. A partir de las acciones &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/25\/confirman-dos-casos-positivos-con-covid19-en-centro-penitenciario-varonil\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qro","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4272"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4272\/revisions"}],"predecessor-version":[{"id":4274,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4272\/revisions\/4274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4273"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}