{"id":4389,"date":"2020-07-27T13:35:34","date_gmt":"2020-07-27T18:35:34","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4389"},"modified":"2020-07-27T13:35:35","modified_gmt":"2020-07-27T18:35:35","slug":"tom-hanks-y-su-esposa-reciben-la-ciudadania-griega","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/27\/tom-hanks-y-su-esposa-reciben-la-ciudadania-griega\/","title":{"rendered":"Tom Hanks y su esposa reciben la ciudadan\u00eda griega"},"content":{"rendered":"\n<p><strong>El primer ministro Kyriakos Mitsotakis public\u00f3 una foto en la que \u00e9l y su esposa, Mareva Grabowski-Mitsotaki, aparec\u00edan con Hanks y Wilson, quienes mostraban sus nuevos pasaportes<\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Un motivo de orgullo para los griegos fue salpicado por la pol\u00e9mica el lunes, cuando un partido opositor critic\u00f3 al primer ministro del pa\u00eds por usar un helic\u00f3ptero militar durante un viaje para celebrar la ciudadan\u00eda griega del actor Tom Hanks y su esposa, Rita Wilson.<\/p>\n\n\n\n<p>El domingo, en Instagram, el primer ministro Kyriakos Mitsotakis public\u00f3 una foto en la que \u00e9l y su esposa, Mareva Grabowski-Mitsotaki, aparec\u00edan con Hanks y Wilson, quienes mostraban sus nuevos pasaportes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cRita Wilson y Tom Hanks son ahora orgullosos ciudadanos griegos\u201d, escribi\u00f3 Mitsotakis en el post.<\/p><\/blockquote>\n\n\n\n<p>Grecia le ofreci\u00f3 la ciudadan\u00eda a Hanks, Wilson y sus dos hijos en reconocimiento a su ayuda recaudando fondos para las v\u00edctimas de un incendio forestal mort\u00edfero cerca de Atenas en 2018.<\/p>\n\n\n\n<p>Wilson, una actriz y productora, es de origen griego y b\u00falgaro.<\/p>\n\n\n\n<p>El vocero del gobierno Stelios Petsas dijo el lunes que el primer ministro y su esposa hab\u00edan tomado un vuelo comercial el s\u00e1bado para viajar a la isla de Paros, y despu\u00e9s viajaron a la cercana Ant\u00edparos, donde Hanks y Wilson tienen una casa vacacional. Entonces usaron un helic\u00f3ptero militar para llegar al antiguo teatro de Epidaurus el domingo para ver una funci\u00f3n de una tragedia griega.<\/p>\n\n\n\n<p>El principal partido opositor de izquierda, Syriza, acus\u00f3 al primer ministro de usar helic\u00f3pteros del ej\u00e9rcito como un \u201cradio taxi personal\u201d.<\/p>\n\n\n\n<p>Petsas argumenta que Mitsotakis cumpl\u00eda con sus deberes de primer ministro al asistir a un \u201cimportante evento cultural\u201d.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer ministro Kyriakos Mitsotakis public\u00f3 una foto en la que \u00e9l y su esposa, Mareva Grabowski-Mitsotaki, aparec\u00edan con Hanks y Wilson, quienes mostraban sus nuevos pasaportes Redacci\u00f3n Un motivo &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/27\/tom-hanks-y-su-esposa-reciben-la-ciudadania-griega\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-4389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4389"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4389\/revisions"}],"predecessor-version":[{"id":4394,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4389\/revisions\/4394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4393"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}