{"id":4401,"date":"2020-07-27T13:39:58","date_gmt":"2020-07-27T18:39:58","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4401"},"modified":"2020-07-27T13:40:00","modified_gmt":"2020-07-27T18:40:00","slug":"termometro-infrarrojo-no-mata-neuronas-insiste-sector-salud","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/27\/termometro-infrarrojo-no-mata-neuronas-insiste-sector-salud\/","title":{"rendered":"Term\u00f3metro infrarrojo no mata neuronas, insiste Sector Salud"},"content":{"rendered":"\n<p>Una vez m\u00e1s las autoridades de salud hicieron \u00e9nfasis en que la toma de la temperatura en la frente de las personas de ninguna manera tiene efectos secundarios en la gente.<\/p>\n\n\n\n<p>En este sentido, la directora de Servicios de Salud del Estado de Quer\u00e9taro, Martina P\u00e9rez Rend\u00f3n, subray\u00f3 el modo de funcionamiento de estos dispositivos, consistente en una luz infrarroja y no l\u00e1ser, como se ha venido creyendo.<\/p>\n\n\n\n<p>La funcionaria estatal insisti\u00f3 en que la temperatura se debe tomar en alguna parte expuesta de la piel, de preferencia en la frente.<\/p>\n\n\n\n<p>\u201c\u00bfEn d\u00f3nde se debe de aplicar? En cualquier lugar de la piel que est\u00e9 expuesta, de preferencia se hace en la frente, hay mucha gente que se niega que se la midan en la frente; recuerden que est\u00e9 es un term\u00f3metro que funciona con infrarrojo, no son l\u00e1ser, no penetran el cr\u00e1neo\u201d, insisti\u00f3 P\u00e9rez Rend\u00f3n.<\/p>\n\n\n\n<p>Finalmente manifest\u00f3 que seguir\u00e1n insistiendo en ese mecanismo como medida de prevenci\u00f3n en el acceso a cualquier tipo de establecimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vez m\u00e1s las autoridades de salud hicieron \u00e9nfasis en que la toma de la temperatura en la frente de las personas de ninguna manera tiene efectos secundarios en la &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/27\/termometro-infrarrojo-no-mata-neuronas-insiste-sector-salud\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qro","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4401"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4401\/revisions"}],"predecessor-version":[{"id":4404,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4401\/revisions\/4404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4403"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}