{"id":4586,"date":"2020-07-30T07:45:27","date_gmt":"2020-07-30T12:45:27","guid":{"rendered":"https:\/\/a3noticias.com.mx\/sandbox\/?p=4586"},"modified":"2020-07-30T07:45:28","modified_gmt":"2020-07-30T12:45:28","slug":"la-scjn-rechazo-un-amparo-sobre-el-aborto","status":"publish","type":"post","link":"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/30\/la-scjn-rechazo-un-amparo-sobre-el-aborto\/","title":{"rendered":"La SCJN rechaz\u00f3 un amparo sobre el aborto"},"content":{"rendered":"\n<p><strong>La Suprema Corte de Justicia de la Naci\u00f3n rechaz\u00f3 un amparo sobre el aborto en Veracruz que pretend\u00eda que ese estado legislara sobre el tema teniendo en cuenta las convenciones internacionales firmadas por M\u00e9xico<\/strong><\/p>\n\n\n\n<p><strong><em>Redacci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Los grupos pro-vida celebraron la decisi\u00f3n por considerar que el alto tribunal respetaba las competencias de los estados, pero organizaciones feministas criticaron que, una vez m\u00e1s, el alto tribunal argumente problemas t\u00e9cnicos y de forma para esquivar pronunciarse sobre el fondo de este controvertido tema.<\/p>\n\n\n\n<p>El aborto en M\u00e9xico s\u00f3lo est\u00e1 permitido en las 12 primeras semanas en Ciudad de M\u00e9xico y Oaxaca, pero es legal en todo el pa\u00eds en caso de que la mujer haya sido violada sin que la ley federal establezca un plazo para llevarlo a cabo.<\/p>\n\n\n\n<p>Veracruz, sin embargo, es de los m\u00e1s conservadores y aunque fuera por violaci\u00f3n s\u00f3lo lo permit\u00eda en los primeros 90 d\u00edas y si hay denuncia previa. Este era uno de los puntos que el ponente del proyecto, el ministro Juan Luis Gonz\u00e1lez Alc\u00e1ntara, consideraba que era discriminatorio para las veracruzanas con respecto al resto de las mexicanas.<\/p>\n\n\n\n<p>El recurso fue rechazado por cuatro votos en contra con el argumento de que no hab\u00eda omisi\u00f3n de legislar por parte del congreso veracruzano porque ya existe una ley sobre el tema. S\u00f3lo Gonz\u00e1lez Alc\u00e1ntara vot\u00f3 a favor y argument\u00f3 lo procedente del amparo al considerar que la legislaci\u00f3n actual de Veracruz es contraria al derecho a la dignidad y a la salud de las mujeres y a las convenciones internacionales firmadas por M\u00e9xico.<\/p>\n\n\n\n<p>Seg\u00fan explic\u00f3 a AP Ver\u00f3nica Cruz, abogada y directora de la ONG Las Libres, el ampar\u00f3 que lleg\u00f3 a la corte \u201cno iba a despenalizar el aborto, no iba a declarar inconstitucional del delito de aborto\u00bb, sino que pretend\u00eda decir a Veracruz que legislara acorde a una recomendaci\u00f3n de finales de 2017 del gobierno federal.<\/p>\n\n\n\n<p>No obstante, esa recomendaci\u00f3n \u2014fruto de una alerta de g\u00e9nero, una especie de declaratoria de emergencia que activa ciertos instrumentos cuando se exacerba la violencia contra las mujeres en determinados puntos de M\u00e9xico\u2014 instaba a despenalizar la interrupci\u00f3n del embarazo en las doce primeras semanas en caso de violaci\u00f3n o por cuestiones de salud de la mujer.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cCuando no quieren resolver sobre el aborto siempre dicen que es por temas t\u00e9cnicos\u201d, critic\u00f3 esta abogada que recuerda que el alto tribunal nunca se ha pronunciado ni a favor ni en contra sobre el fondo del asunto, aunque gracias a algunos de sus fallos se logr\u00f3 la libertad de mujeres que llevaban a\u00f1os injustamente encarceladas.<\/p><\/blockquote>\n\n\n\n<p>Las organizaciones feministas confiaban en que un apoyo a este amparo supusiera un precedente para avanzar hacia la despenalizaci\u00f3n del aborto no s\u00f3lo en Veracruz sino en otros estados.<\/p>\n\n\n\n<p>Varias decenas de personas apostadas frente a la sede de la Corte en Ciudad de M\u00e9xico gritaban consignas en favor de Cristo Rey o la Virgen y celebraron la decisi\u00f3n del tribunal.<\/p>\n\n\n\n<p>En un comunicado, organizaciones pro-vida elogiaron que los ministros optaran por \u201csalvaguardar la soberan\u00eda de los estados y su libre configuraci\u00f3n, respetando la voluntad del pueblo de Veracruz que, en su Constituci\u00f3n local, reconoce el Derecho a la Vida desde la concepci\u00f3n hasta la muerte natural\u201d.<\/p>\n\n\n\n<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador no se ha pronunciado abiertamente sobre el tema, pero siempre se ha mostrado muy conservador en estas cuestiones, en linea con la Iglesia cat\u00f3lica y otros grupos religiosos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Suprema Corte de Justicia de la Naci\u00f3n rechaz\u00f3 un amparo sobre el aborto en Veracruz que pretend\u00eda que ese estado legislara sobre el tema teniendo en cuenta las convenciones &hellip; <a href=\"https:\/\/a3noticias.com.mx\/sandbox\/2020\/07\/30\/la-scjn-rechazo-un-amparo-sobre-el-aborto\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nal","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/comments?post=4586"}],"version-history":[{"count":1,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4586\/revisions"}],"predecessor-version":[{"id":4588,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/posts\/4586\/revisions\/4588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media\/4587"}],"wp:attachment":[{"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/media?parent=4586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/categories?post=4586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a3noticias.com.mx\/sandbox\/wp-json\/wp\/v2\/tags?post=4586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}